{"id":2210,"date":"2022-01-25T15:24:47","date_gmt":"2022-01-25T20:24:47","guid":{"rendered":"https:\/\/treize.pro\/?page_id=2210"},"modified":"2026-01-13T16:33:14","modified_gmt":"2026-01-13T21:33:14","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/treize.pro\/en\/privacy-policy\/","title":{"rendered":"Privacy policy"},"content":{"rendered":"<p>Nom de l&#8217;entreprise : Treize web inc.<br \/>\nURL du site web : treize.pro<br \/>\nType de site : Site web informatif<\/p>\n<h2><span class=\"text-h3\">Le but de cette politique de confidentialit\u00e9<\/span><\/h2>\n<p>Le but de cette politique de confidentialit\u00e9 est d&#8217;informer les utilisateurs de notre site des donn\u00e9es personnelles que nous recueillerons ainsi que les informations suivantes, le cas \u00e9ch\u00e9ant :<\/p>\n<ol>\n<li>Les donn\u00e9es personnelles que nous recueillerons<\/li>\n<li>L\u2019utilisation des donn\u00e9es recueillies<\/li>\n<li>Qui a acc\u00e8s aux donn\u00e9es recueillies<\/li>\n<li>Les droits des utilisateurs du site<\/li>\n<li>La politique de cookies du site<\/li>\n<\/ol>\n<p>Cette politique de confidentialit\u00e9 fonctionne parall\u00e8lement aux conditions g\u00e9n\u00e9rales d\u2019utilisation de notre site.<\/p>\n<h2><span class=\"text-h3\">Lois applicables<\/span><\/h2>\n<p>Cette politique est conforme aux lois \u00e9nonc\u00e9es dans la\u00a0loi sur la protection des renseignements personnels et les documents \u00e9lectroniques\u00a0(LPRPDE).<\/p>\n<p>Pour les r\u00e9sidents du Qu\u00e9bec, cette politique de confidentialit\u00e9 vise \u00e0 se conformer \u00e0 la Loi modernisant des dispositions l\u00e9gislatives en mati\u00e8re de protection des renseignements personnels dans le secteur priv\u00e9 (Loi 25). S\u2019il y a des incoh\u00e9rences entre ce document et la Loi 25, la l\u00e9gislation de l\u2019\u00c9tat s\u2019appliquera. Si nous constatons des incoh\u00e9rences, nous modifierons notre politique pour nous conformer \u00e0 la loi pertinente.<\/p>\n<p>Pour les r\u00e9sidents des pays de l\u2019UE, le\u00a0R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es\u00a0(RGDP) r\u00e9git toutes les politiques de protection des donn\u00e9es, quel que soit l\u2019endroit o\u00f9 se trouve le site. La pr\u00e9sente politique de confidentialit\u00e9 vise \u00e0 se conformer au RGDP. S\u2019il y a des incoh\u00e9rences entre la pr\u00e9sente politique et le RGDP, le RGDP s\u2019appliquera.<\/p>\n<p>Pour les r\u00e9sidents de l\u2019\u00c9tat de Californie, cette politique de confidentialit\u00e9 vise \u00e0 se conformer \u00e0 la\u00a0California Consumer Privacy Act (CCPA). S\u2019il y a des incoh\u00e9rences entre ce document et la\u00a0CCPA, la l\u00e9gislation de l\u2019\u00c9tat s\u2019appliquera. Si nous constatons des incoh\u00e9rences, nous modifierons notre politique pour nous conformer \u00e0 la loi pertinente.<\/p>\n<h2><span class=\"text-h3\">Consentement<\/span><\/h2>\n<p>Les utilisateurs conviennent qu\u2019en utilisant notre site, ils consentent \u00e0 :<\/p>\n<ol>\n<li>les conditions \u00e9nonc\u00e9es dans la pr\u00e9sente politique de confidentialit\u00e9 et<\/li>\n<li>la collecte, l\u2019utilisation et la conservation des donn\u00e9es \u00e9num\u00e9r\u00e9es dans la pr\u00e9sente politique.<\/li>\n<\/ol>\n<h2><span class=\"text-h3\">Donn\u00e9es personnelles que nous collectons<\/span><\/h2>\n<h3><span class=\"text-h5\">Donn\u00e9es collect\u00e9es automatiquement<\/span><\/h3>\n<p>Lorsque vous visitez et utilisez notre site, nous pouvons automatiquement recueillir et conserver les renseignements suivants :<\/p>\n<ol>\n<li>Adresse IP<\/li>\n<li>Lieu<\/li>\n<li>D\u00e9tails mat\u00e9riels et logiciels<\/li>\n<li>Liens un utilisateur clique tout en utilisant le site<\/li>\n<li>Contenu que l\u2019utilisateur consulte sur votre site<\/li>\n<\/ol>\n<h3><span class=\"text-h5\">Donn\u00e9es recueillies de fa\u00e7on non automatique<\/span><\/h3>\n<p>Nous pouvons \u00e9galement collecter les donn\u00e9es suivantes lorsque vous effectuez certaines fonctions sur notre site\u00a0:<\/p>\n<ol>\n<li>Pr\u00e9nom et nom<\/li>\n<li>Email<\/li>\n<li>Num\u00e9ro de t\u00e9l\u00e9phone<\/li>\n<li>Renseignements sur un projet<\/li>\n<\/ol>\n<p>Ces donn\u00e9es peuvent \u00eatre recueillies au moyen des m\u00e9thodes suivantes\u00a0:<\/p>\n<ul>\n<li>Formulaire de demande de soumission<\/li>\n<\/ul>\n<p>Veuillez noter que nous ne collectons que les donn\u00e9es qui nous aident \u00e0 atteindre l\u2019objectif \u00e9nonc\u00e9 dans cette politique de confidentialit\u00e9. Nous ne recueillerons pas de donn\u00e9es suppl\u00e9mentaires sans vous en informer au pr\u00e9alable.<\/p>\n<h2><span class=\"text-h3\">Comment nous utilisons les donn\u00e9es personnelles<\/span><\/h2>\n<p>Les donn\u00e9es personnelles recueillies sur notre site seront utilis\u00e9es uniquement aux fins pr\u00e9cis\u00e9es dans la pr\u00e9sente politique ou indiqu\u00e9es sur les pages pertinentes de notre site. Nous n\u2019utiliserons pas vos donn\u00e9es au-del\u00e0 de ce que nous divulguerons.<\/p>\n<p>Les donn\u00e9es que nous recueillons automatiquement sont utilis\u00e9es aux fins suivantes\u00a0:<\/p>\n<ol>\n<li>Analytique<\/li>\n<li>Performance<\/li>\n<li>Fonctionnelle<\/li>\n<li>Publicit\u00e9<\/li>\n<\/ol>\n<p>Les donn\u00e9es que nous recueillons lorsque l\u2019utilisateur ex\u00e9cute certaines fonctions peuvent \u00eatre utilis\u00e9es aux fins suivantes\u00a0:<\/p>\n<ol>\n<li>Communication<\/li>\n<\/ol>\n<h2><span class=\"text-h3\">Avec qui nous partageons les donn\u00e9es personnelles<\/span><\/h2>\n<h3><span class=\"text-h5\">Employ\u00e9s<\/span><\/h3>\n<p>Nous pouvons divulguer \u00e0 tout membre de notre organisation les donn\u00e9es utilisateur dont il a raisonnablement besoin pour r\u00e9aliser les objectifs \u00e9nonc\u00e9s dans la pr\u00e9sente politique.<\/p>\n<h3><span class=\"text-h5\">Tierces parties<\/span><\/h3>\n<p>Nous pouvons partager les donn\u00e9es utilisateur avec les tiers suivants\u00a0:<\/p>\n<p>Nous pouvons partager les donn\u00e9es utilisateur avec des tiers aux fins suivantes\u00a0:<\/p>\n<p>Les tiers ne seront pas en mesure d\u2019acc\u00e9der aux donn\u00e9es des utilisateurs au-del\u00e0 de ce qui est raisonnablement n\u00e9cessaire pour atteindre l\u2019objectif donn\u00e9.<\/p>\n<h3><span class=\"text-h5\">Autres divulgations<\/span><\/h3>\n<p>Nous nous engageons \u00e0 ne pas vendre ou partager vos donn\u00e9es avec des tiers, sauf dans les cas suivants\u00a0:<\/p>\n<ol>\n<li>si la loi l&#8217;exige<\/li>\n<li>si elle est requise pour toute proc\u00e9dure judiciaire<\/li>\n<li>pour prouver ou prot\u00e9ger nos droits l\u00e9gaux<\/li>\n<li>\u00e0 des acheteurs ou des acheteurs potentiels de cette soci\u00e9t\u00e9 dans le cas o\u00f9 nous cherchons \u00e0 la vendre la soci\u00e9t\u00e9<\/li>\n<\/ol>\n<p>Si vous suivez des hyperliens de notre site vers un autre site, veuillez noter que nous ne sommes pas responsables et n\u2019avons pas de contr\u00f4le sur leurs politiques et pratiques de confidentialit\u00e9.<\/p>\n<h2><span class=\"text-h3\">Combien de temps nous stockons les donn\u00e9es personnelles<\/span><\/h2>\n<p>Nous ne conservons pas les donn\u00e9es des utilisateurs au-del\u00e0 de ce qui est n\u00e9cessaire pour atteindre les fins pour lesquelles elles sont recueillies.<\/p>\n<h2><span class=\"text-h3\">Comment nous prot\u00e9geons vos donn\u00e9es personnelles<\/span><\/h2>\n<p>Afin d\u2019assurer la protection de votre s\u00e9curit\u00e9, toutes les donn\u00e9es stock\u00e9es dans notre syst\u00e8me sont bien s\u00e9curis\u00e9es et ne sont accessibles qu\u2019\u00e0 nos employ\u00e9s. Nos employ\u00e9s sont li\u00e9s par des accords de confidentialit\u00e9 stricts et une violation de cet accord entra\u00eenerait le licenciement de l&#8217;employ\u00e9.<\/p>\n<p>Alors que nous prenons toutes les pr\u00e9cautions raisonnables pour nous assurer que nos donn\u00e9es d\u2019utilisateur sont s\u00e9curis\u00e9es et que les utilisateurs sont prot\u00e9g\u00e9s, il reste toujours du risque de pr\u00e9judice. L\u2019Internet en sa totalit\u00e9 peut \u00eatre, parfois, peu s\u00fbr et donc nous sommes incapables de garantir la s\u00e9curit\u00e9 des donn\u00e9es des utilisateurs au-del\u00e0 de ce qui est raisonnablement pratique.<\/p>\n<h2><span class=\"text-h3\">Mineurs<\/span><\/h2>\n<p>Pour les r\u00e9sidents de l\u2019UE, le RGPD pr\u00e9cise que les personnes de moins de 15 ans sont consid\u00e9r\u00e9es comme des mineurs aux fins de la collecte de donn\u00e9es. Les mineurs doivent avoir le consentement d\u2019un repr\u00e9sentant l\u00e9gal pour que leurs donn\u00e9es soient recueillies, trait\u00e9es et utilis\u00e9es.<\/p>\n<h2><span class=\"text-h3\">Vos droits en tant qu\u2019utilisateur<\/span><\/h2>\n<p>En tant qu\u2019utilisateur, vous avez le droit d\u2019acc\u00e9der \u00e0 toutes vos donn\u00e9es personnelles que nous avons collect\u00e9es. En outre, vous avez le droit de mettre \u00e0 jour ou de corriger toute donn\u00e9e personnelle en notre possession \u00e0 condition qu\u2019elle soit acceptable en vertu de la loi.<\/p>\n<p>Vous pouvez choisir de supprimer ou de modifier votre consentement \u00e0 la collecte et \u00e0 l\u2019utilisation des donn\u00e9es en tout temps, pourvu qu\u2019il soit l\u00e9galement acceptable de le faire et que vous nous en ayez inform\u00e9 dans un d\u00e9lai raisonnable.<\/p>\n<h2><span class=\"text-h3\">Comment modifier, supprimer ou contester les donn\u00e9es recueillies<\/span><\/h2>\n<p>Si vous souhaitez que vos renseignements soient supprim\u00e9s ou modifi\u00e9s d\u2019une fa\u00e7on ou d\u2019une autre, veuillez communiquer avec notre agent de protection de la vie priv\u00e9e ici :<\/p>\n<p>Jean-Fran\u00e7ois Sauriol<br \/>\n&#x6a;&#x66;&#115;&#97;ur&#x69;&#x6f;&#x6c;&#64;tr&#x65;&#x69;&#x7a;&#101;&#46;p&#x72;&#x6f;<br \/>\n(438) 940-2500<\/p>\n<h2><span class=\"text-h3\">Politique sur les cookies<\/span><\/h2>\n<p>Un cookie est un petit fichier, stock\u00e9 sur le disque dur d\u2019un utilisateur par le site Web. Son but est de recueillir des donn\u00e9es relatives aux habitudes de navigation de l\u2019utilisateur.<\/p>\n<p>Nous utilisons les types de cookies suivants sur notre site\u00a0:<\/p>\n<ol>\n<li>Cookies fonctionnels : Nous les utilisons pour m\u00e9moriser toutes les s\u00e9lections que vous faites sur notre site afin qu\u2019elles soient sauvegard\u00e9es pour vos prochaines visites.<\/li>\n<li>Cookies tiers : Nous utilisons \u00e9galement des cookies tiers qui nous aident \u00e0 analyser la fa\u00e7on dont vous utilisez ce site web, \u00e0 enregistrer vos pr\u00e9f\u00e9rences et \u00e0 vous fournir du contenu et des publicit\u00e9s adapt\u00e9s.<\/li>\n<\/ol>\n<p>Vous pouvez choisir de d\u00e9sactiver les cookies enti\u00e8rement ou partiellement, mais cela peut diminuer la qualit\u00e9 de votre exp\u00e9rience d\u2019utilisation.<\/p>\n<h2><span class=\"text-h3\">Modifications<\/span><\/h2>\n<p>Cette politique de confidentialit\u00e9 peut \u00eatre modifi\u00e9e \u00e0 l\u2019occasion afin de maintenir la conformit\u00e9 avec la loi et de tenir compte de tout changement \u00e0 notre processus de collecte de donn\u00e9es. Nous recommandons \u00e0 nos utilisateurs de v\u00e9rifier notre politique de temps \u00e0 autre pour s\u2019assurer qu\u2019ils soient inform\u00e9s de toute mise \u00e0 jour. Au besoin, nous pouvons informer les utilisateurs par courriel des changements apport\u00e9s \u00e0 cette politique.<\/p>\n<h2><span class=\"text-h3\">Contact<\/span><\/h2>\n<p>Si vous avez des questions \u00e0 nous poser, n\u2019h\u00e9sitez pas \u00e0 communiquer avec nous en utilisant ce qui suit :<\/p>\n<p>(438) 940-2500<br \/>\n&#105;&#x6e;&#102;&#x6f;&#64;&#x74;&#114;&#x65;i&#x7a;e&#x2e;p&#x72;o<br \/>\n2025 rue Parthenais, local 306, Montr\u00e9al, QC H2K 3T2, Canada<\/p>\n<p>Date d\u2019entr\u00e9e en vigueur\u00a0:\u00a0le 24 juillet 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nom de l&#8217;entreprise : Treize web inc. URL du site web : treize.pro Type de site : Site web informatif Le but de cette politique de confidentialit\u00e9 Le but de cette politique de confidentialit\u00e9 est d&#8217;informer les utilisateurs de notre site des donn\u00e9es personnelles que nous recueillerons ainsi que les informations suivantes, le cas \u00e9ch\u00e9ant [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-2210","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/treize.pro\/en\/wp-json\/wp\/v2\/pages\/2210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/treize.pro\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/treize.pro\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/treize.pro\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/treize.pro\/en\/wp-json\/wp\/v2\/comments?post=2210"}],"version-history":[{"count":8,"href":"https:\/\/treize.pro\/en\/wp-json\/wp\/v2\/pages\/2210\/revisions"}],"predecessor-version":[{"id":5912,"href":"https:\/\/treize.pro\/en\/wp-json\/wp\/v2\/pages\/2210\/revisions\/5912"}],"wp:attachment":[{"href":"https:\/\/treize.pro\/en\/wp-json\/wp\/v2\/media?parent=2210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}